{"id":7226,"date":"2025-03-11T10:24:39","date_gmt":"2025-03-11T10:24:39","guid":{"rendered":"https:\/\/jaso.com\/elevation\/?p=7226"},"modified":"2026-03-31T10:11:12","modified_gmt":"2026-03-31T10:11:12","slug":"celebramos-nuestro-50-aniversario-en-bauma","status":"publish","type":"post","link":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/","title":{"rendered":"Celebramos nuestro 50 aniversario en bauma"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Del 7 al 13 de abril en M\u00fanich, bauma ser\u00e1 el escenario perfecto para celebrar nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.<\/h5>\n\n\n\n<p>Fieles a nuestro compromiso con la innovaci\u00f3n y el desarrollo de soluciones de elevaci\u00f3n eficientes y optimizadas para los mercados de la construcci\u00f3n, la energ\u00eda e\u00f3lica y la industria, presentaremos nuestras \u00faltimas novedades en el <strong>stand FS.1003\/8<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Flat Top<strong> J165.8<\/strong><\/li>\n\n\n\n<li>Plataforma de transporte <strong>GPT27<\/strong><\/li>\n\n\n\n<li>Plataforma de trabajo <strong>GP40 con el innovador sistema monorra\u00edl<\/strong><\/li>\n\n\n\n<li>Nuevo JASO <strong>SmartLink<\/strong><\/li>\n\n\n\n<li>Renovada cabina <strong>\u2018HORIZON\u2019<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital-1024x576.jpg\" alt=\"\" class=\"wp-image-7227\" srcset=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital-1024x576.jpg 1024w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital-300x169.jpg 300w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital-768x432.jpg 768w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital-1536x864.jpg 1536w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/2-panel-bauma_J165-8_digital.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>J165.8: innovaci\u00f3n y versatilidad<\/strong><\/h3>\n\n\n\n<p>Un nuevo modelo de gr\u00faa se une a nuestra gama Flat Top. Esta gr\u00faa J165.8 Flat Top tiene:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una carga m\u00e1xima de 8 toneladas<\/li>\n\n\n\n<li>Una carga en punta de 1,92 toneladas<\/li>\n\n\n\n<li>Longitudes de pluma entre los 30 y 60 metros, que pueden ampliarse en incrementos de 5 metros<\/li>\n\n\n\n<li>Contrapluma extremadamente corta de 12,9 metros<\/li>\n\n\n\n<li>Contrapesos dispuestos en plano<\/li>\n\n\n\n<li>Una altura autoestable de 53,10 metros con un sistema de torre de 1,75 metros<\/li>\n\n\n\n<li>Un mecanismo de alto rendimiento, con una impresionante velocidad m\u00e1xima de 177 m\/min (45 kW)<\/li>\n\n\n\n<li>Baja huella de carbono \u2013 ECO-Mode con bajo consumo de 31 KVA<\/li>\n\n\n\n<li>Optimizada para transporte y montaje inteligente<\/li>\n<\/ul>\n\n\n\n<p>Su dise\u00f1o optimiza el peso de los componentes, facilitando un montaje r\u00e1pido y eficiente incluso en \u00e1reas congestionadas. Adem\u00e1s, incorpora tecnolog\u00edas innovadoras como micro velocidad, giro progresivo y Smartlink, garantizando eficiencia, seguridad y un bajo impacto ambiental.<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Elevadores para construcci\u00f3n GPT27 y GP40 con sistema monorra\u00edl<\/strong><\/h3>\n\n\n\n<p>Como l\u00edderes en sistemas de Rack &amp; Pinion en el sector e\u00f3lico, ofrecemos tambi\u00e9n elevadores para construcci\u00f3n con una cartera de productos renovada, que incluye elevadores de personal y material, plataformas de transporte y de trabajo, montacargas y elevadores de gr\u00faa torre.<\/p>\n\n\n\n<p>En esta edici\u00f3n, presentaremos la nueva plataforma de transporte GPT27 y la plataforma de trabajo GP40 con el nuevo sistema monorra\u00edl.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital-1024x576.jpg\" alt=\"\" class=\"wp-image-7229\" srcset=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital-1024x576.jpg 1024w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital-300x169.jpg 300w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital-768x432.jpg 768w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital-1536x864.jpg 1536w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/3-panel-bauma_GPT27_digital.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GPT27<\/strong>: con una capacidad de carga m\u00e1xima de 2.700 kg, combina rentabilidad y robustez, y permite elevar cargas y personas r\u00e1pidamente a diferentes alturas, optimizando la productividad al m\u00e1ximo. Entre sus caracter\u00edsticas destacan:\n<ul class=\"wp-block-list\">\n<li>Carga m\u00e1xima: 2.700 kg<\/li>\n\n\n\n<li>N\u00famero m\u00e1ximo de personas: 7<\/li>\n\n\n\n<li>Dimensiones de la cabina interna: 3,2\u00d71,5 m<\/li>\n\n\n\n<li>Mecanismo de alto rendimiento (3\u00d75,5 kW)<\/li>\n\n\n\n<li>Velocidad de 12 m\/min para personas y de 20 m\/min \u2013 material<\/li>\n\n\n\n<li>Altura m\u00e1xima: 200 m \u2013 sistema de m\u00e1stil MN65<\/li>\n\n\n\n<li>Distancia entre anclajes: cada 9 m<\/li>\n\n\n\n<li>Sistema de m\u00e1stil com\u00fan con otros equipos<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital-1024x576.jpg\" alt=\"\" class=\"wp-image-7231\" srcset=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital-1024x576.jpg 1024w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital-300x169.jpg 300w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital-768x432.jpg 768w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital-1536x864.jpg 1536w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/4-panel-bauma_GP40_digital.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GP40 con monorra\u00edl<\/strong>: presentamos una soluci\u00f3n revolucionaria destinada a transformar las operaciones de revestimiento de fachadas. Al integrar ingeniosamente un sistema de monorra\u00edl con nuestras reconocidas plataformas de trabajo sobre m\u00e1stil, el monorra\u00edl facilita el movimiento eficiente de materiales y personal a lo largo de la extensi\u00f3n vertical del edificio, optimizando todo el proceso de revestimiento con gran precisi\u00f3n. Las caracter\u00edsticas del sistema monorra\u00edl son:\n<ul class=\"wp-block-list\">\n<li>Carga m\u00e1xima: 500 kg<\/li>\n\n\n\n<li>Longitud m\u00e1xima de la v\u00eda: 29,56 m para la configuraci\u00f3n de m\u00e1stil doble y 10,12 m para la de m\u00e1stil simple<\/li>\n\n\n\n<li>Altura m\u00e1xima: 350 m \u2013 sistema de m\u00e1stil MR50<\/li>\n\n\n\n<li>Distancia entre anclajes: cada 6 m<\/li>\n\n\n\n<li>Montaje inteligente<\/li>\n\n\n\n<li>Robusto, modular, c\u00f3modo y seguro<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital-1024x576.jpg\" alt=\"\" class=\"wp-image-7233\" srcset=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital-1024x576.jpg 1024w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital-300x169.jpg 300w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital-768x432.jpg 768w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital-1536x864.jpg 1536w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/5-panel-bauma_smartlink_digital.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Nuevo JASO SmartLink<\/strong><\/h3>\n\n\n\n<p>JASO SmartLink es un sistema integral de monitoreo de gr\u00faas torre que te permite obtener informaci\u00f3n precisa sobre las operaciones de tu gr\u00faa torre.<\/p>\n\n\n\n<p>Te permite controlar los tiempos ineficientes, asegurar el uso correcto de tu gr\u00faa torre y prevenir costosas aver\u00edas. Al maximizar la eficiencia, la productividad y el beneficio, puedes gestionar con confianza tu flota de gr\u00faas torre, reducir el tiempo de inactividad y mejorar la seguridad, todo mientras optimizas tus resultados.<\/p>\n\n\n\n<p>Con JASO SmartLink, obtienes una ventaja competitiva al aprovechar el poder de los datos para tomar decisiones informadas, reducir los costos operativos y mejorar el rendimiento general. Eleva las operaciones de tu gr\u00faa torre con JASO SmartLink y experimenta la diferencia en control, eficiencia y rentabilidad.<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital-1024x576.jpg\" alt=\"\" class=\"wp-image-7235\" srcset=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital-1024x576.jpg 1024w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital-300x169.jpg 300w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital-768x432.jpg 768w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital-1536x864.jpg 1536w, https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/6-panel-bauma_cabin-horizon_digital.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Nueva cabina \u2018HORIZON\u2019<\/strong><\/h3>\n\n\n\n<p>Por \u00faltimo, desvelaremos nuestra nueva cabina \u2018HORIZON\u2019. Un nuevo dise\u00f1o que optimizar\u00e1 el confort y la visi\u00f3n de los operarios, y que podr\u00e1s descubrir en exclusiva en bauma.<\/p>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\u00a1Ven a celebrar nuestro 50 cumplea\u00f1os en el stand FS.1003\/8!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 7 al 13 de abril en M\u00fanich, bauma ser\u00e1 el escenario perfecto para celebrar nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes. Fieles a nuestro compromiso con la innovaci\u00f3n y el desarrollo de soluciones de elevaci\u00f3n eficientes y optimizadas para los mercados de la construcci\u00f3n, la energ\u00eda e\u00f3lica y la industria, presentaremos [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":7238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[137,1,37],"tags":[],"class_list":["post-7226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","category-actualidad","category-destacados-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebramos nuestro 50 aniversario en bauma<\/title>\n<meta name=\"description\" content=\"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebramos nuestro 50 aniversario en bauma\" \/>\n<meta property=\"og:description\" content=\"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/\" \/>\n<meta property=\"og:site_name\" content=\"Fabricante de sistemas de elevaci\u00f3n - JASO Elevation Systems\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T10:24:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T10:11:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"andreagarcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"andreagarcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/\"},\"author\":{\"name\":\"andreagarcia\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#\\\/schema\\\/person\\\/6dd4fb91f453a26e54104916a6667c71\"},\"headline\":\"Celebramos nuestro 50 aniversario en bauma\",\"datePublished\":\"2025-03-11T10:24:39+00:00\",\"dateModified\":\"2026-03-31T10:11:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/1-noticia_jaso_bauma-2025_1000x585.jpg\",\"articleSection\":[\"Construcci\u00f3n\",\"Actualidad\",\"destacados-categoria\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/\",\"url\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/\",\"name\":\"Celebramos nuestro 50 aniversario en bauma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/1-noticia_jaso_bauma-2025_1000x585.jpg\",\"datePublished\":\"2025-03-11T10:24:39+00:00\",\"dateModified\":\"2026-03-31T10:11:12+00:00\",\"description\":\"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/1-noticia_jaso_bauma-2025_1000x585.jpg\",\"contentUrl\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/1-noticia_jaso_bauma-2025_1000x585.jpg\",\"width\":1000,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/actualidad\\\/celebramos-nuestro-50-aniversario-en-bauma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebramos nuestro 50 aniversario en bauma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#website\",\"url\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/\",\"name\":\"JASO Tower Cranes - Fabricantes de gr\u00faas torre\",\"description\":\"Somos un fabricante referente a nivel global. Ofrecemos una completa soluci\u00f3n de sistemas de elevaci\u00f3n..\",\"publisher\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#organization\"},\"alternateName\":\"JASO Tower Cranes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#organization\",\"name\":\"JASO Tower Cranes\",\"alternateName\":\"JASO\",\"url\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jaso_torre.png\",\"contentUrl\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/jaso_torre.png\",\"width\":1200,\"height\":630,\"caption\":\"JASO Tower Cranes\"},\"image\":{\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jaso.com\\\/elevation\\\/#\\\/schema\\\/person\\\/6dd4fb91f453a26e54104916a6667c71\",\"name\":\"andreagarcia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g\",\"caption\":\"andreagarcia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebramos nuestro 50 aniversario en bauma","description":"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/","og_locale":"es_ES","og_type":"article","og_title":"Celebramos nuestro 50 aniversario en bauma","og_description":"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.","og_url":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/","og_site_name":"Fabricante de sistemas de elevaci\u00f3n - JASO Elevation Systems","article_published_time":"2025-03-11T10:24:39+00:00","article_modified_time":"2026-03-31T10:11:12+00:00","og_image":[{"width":1000,"height":585,"url":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg","type":"image\/jpeg"}],"author":"andreagarcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"andreagarcia","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#article","isPartOf":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/"},"author":{"name":"andreagarcia","@id":"https:\/\/jaso.com\/elevation\/#\/schema\/person\/6dd4fb91f453a26e54104916a6667c71"},"headline":"Celebramos nuestro 50 aniversario en bauma","datePublished":"2025-03-11T10:24:39+00:00","dateModified":"2026-03-31T10:11:12+00:00","mainEntityOfPage":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/"},"wordCount":708,"publisher":{"@id":"https:\/\/jaso.com\/elevation\/#organization"},"image":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#primaryimage"},"thumbnailUrl":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg","articleSection":["Construcci\u00f3n","Actualidad","destacados-categoria"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/","url":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/","name":"Celebramos nuestro 50 aniversario en bauma","isPartOf":{"@id":"https:\/\/jaso.com\/elevation\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#primaryimage"},"image":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#primaryimage"},"thumbnailUrl":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg","datePublished":"2025-03-11T10:24:39+00:00","dateModified":"2026-03-31T10:11:12+00:00","description":"Del 7 al 13 de abril en bauma celebraremos nuestro 50 cumplea\u00f1os junto a todos nuestros partners y clientes.","breadcrumb":{"@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#primaryimage","url":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg","contentUrl":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2025\/03\/1-noticia_jaso_bauma-2025_1000x585.jpg","width":1000,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/jaso.com\/elevation\/actualidad\/celebramos-nuestro-50-aniversario-en-bauma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jaso.com\/elevation\/"},{"@type":"ListItem","position":2,"name":"Celebramos nuestro 50 aniversario en bauma"}]},{"@type":"WebSite","@id":"https:\/\/jaso.com\/elevation\/#website","url":"https:\/\/jaso.com\/elevation\/","name":"JASO Tower Cranes - Fabricantes de gr\u00faas torre","description":"Somos un fabricante referente a nivel global. Ofrecemos una completa soluci\u00f3n de sistemas de elevaci\u00f3n..","publisher":{"@id":"https:\/\/jaso.com\/elevation\/#organization"},"alternateName":"JASO Tower Cranes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jaso.com\/elevation\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/jaso.com\/elevation\/#organization","name":"JASO Tower Cranes","alternateName":"JASO","url":"https:\/\/jaso.com\/elevation\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/jaso.com\/elevation\/#\/schema\/logo\/image\/","url":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2022\/10\/jaso_torre.png","contentUrl":"https:\/\/jaso.com\/elevation\/wp-content\/uploads\/2022\/10\/jaso_torre.png","width":1200,"height":630,"caption":"JASO Tower Cranes"},"image":{"@id":"https:\/\/jaso.com\/elevation\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jaso.com\/elevation\/#\/schema\/person\/6dd4fb91f453a26e54104916a6667c71","name":"andreagarcia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/65e4f45bdf3350aa3b55bcce6aaf9da6776ee2e9f9a05ef1d373564e4b3504b4?s=96&d=mm&r=g","caption":"andreagarcia"}}]}},"_links":{"self":[{"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/posts\/7226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/comments?post=7226"}],"version-history":[{"count":1,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/posts\/7226\/revisions"}],"predecessor-version":[{"id":7237,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/posts\/7226\/revisions\/7237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/media\/7238"}],"wp:attachment":[{"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/media?parent=7226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/categories?post=7226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jaso.com\/elevation\/wp-json\/wp\/v2\/tags?post=7226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}